{"id":4236,"date":"2025-04-11T16:58:04","date_gmt":"2025-04-11T15:58:04","guid":{"rendered":"https:\/\/hihotels.it\/camere\/einzimmerwohnung-mit-jacuzzi\/"},"modified":"2025-11-05T12:26:10","modified_gmt":"2025-11-05T11:26:10","slug":"einzimmerwohnung-mit-jacuzzi","status":"publish","type":"camere","link":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/","title":{"rendered":"Einzimmerwohnung mit Jacuzzi"},"content":{"rendered":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;715&#8243; bg_position=&#8220;left top&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;8%&#8220; top_padding_tablet=&#8220;20%&#8220; left_padding_tablet=&#8220;0&#8243; right_padding_tablet=&#8220;0&#8243; top_padding_phone=&#8220;34%&#8220; left_padding_phone=&#8220;0&#8243; right_padding_phone=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; parallax_bg=&#8220;true&#8220; parallax_bg_speed=&#8220;minimum&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;3744&#8243; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-left&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;65vh&#8220; custom_height_tablet=&#8220;45vh&#8220; custom_height_phone=&#8220;45vh&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;8%&#8220; top_padding_tablet=&#8220;4%&#8220; top_padding_phone=&#8220;4%&#8220; translate_x=&#8220;100&#8243; translate_x_tablet=&#8220;0&#8243; translate_x_phone=&#8220;0&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;padding-2-percent&#8220; column_padding_phone=&#8220;padding-2-percent&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-12&#8243; delay=&#8220;300&#8243;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>Einzimmerwohnung mit Jacuzzi<\/h2>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;padding-2-percent&#8220; column_padding_phone=&#8220;padding-2-percent&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;advanced&#8220; border_left_desktop=&#8220;1&#8243; column_border_color=&#8220;#c19d5c&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/02\/hihotels-icon-mt-dark-9ce32f.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h6 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">25qm<\/h6>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/02\/hihotels-icon-person-dark-046684.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h6 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">2 Seiten<\/h6>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;1%&#8220; top_padding_tablet=&#8220;1%&#8220; top_padding_phone=&#8220;1%&#8220; translate_x=&#8220;100&#8243; translate_x_tablet=&#8220;0&#8243; translate_x_phone=&#8220;0&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;padding-2-percent&#8220; column_padding_phone=&#8220;padding-2-percent&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-12&#8243; delay=&#8220;300&#8243;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h5>Mit Balkon und Jacuzzi<\/h5>\n<div class=\"ciaojs-accommodation-notes whitespace-pre-line\">Entdecken Sie die Eleganz unserer ger\u00e4umigen Suite, die \u00fcber eine Panoramaterrasse mit privatem Whirlpool verf\u00fcgt, auf der Sie sich mit einem atemberaubenden Blick auf die Stadt und die Berge entspannen k\u00f6nnen. Das Zimmer bietet eine voll ausgestattete K\u00fcche, ein Badezimmer mit Dusche und alle Annehmlichkeiten eines exklusiven Wohnzimmers. Eine Oase des Friedens und der Ruhe.<\/div>\n<div class=\"ciaojs-accommodation-amenities whitespace-pre-line\"><em><br \/>\n*Im Erlebnis inbegriffen ist der Zugang zu unserem Spa- und Wellnessbereich.<\/em><\/div>\n[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;2vh&#8220;][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; text=&#8220;EIN ANGEBOT ANFORDERN&#8220; url=&#8220;#request&#8220; margin_right=&#8220;10&#8243; css_animation=&#8220;fadeIn&#8220;][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Extra-Color-1&#8243; icon_family=&#8220;none&#8220; text=&#8220;JETZT BUCHEN&#8220; url=&#8220;https:\/\/www.scidoo.com\/preventivov2\/?cod=1705&#038;IDsotto_struttura=1567&#038;lang=0&#8243; css_animation=&#8220;fadeIn&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;advanced&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;center&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; delay=&#8220;150&#8243; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20vh&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h4>S\u00fc\u00dfes Erwachen<\/h4>\n[\/vc_column_text][divider line_type=&#8220;Vertical Line&#8220; divider_color=&#8220;extra-color-2&#8243; custom_height=&#8220;10vh&#8220;][image_with_animation image_url=&#8220;3676&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;50%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; constrain_group_1=&#8220;yes&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;advanced&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_gallery css=&#8220;&#8220; type=&#8220;flickity_style&#8220; images=&#8220;3753,3756,3768,3777,3774,3759,3762,3765,3750,3771,3780,3783,3786,3789,3746&#8243; flickity_spacing=&#8220;default&#8220; flickity_controls=&#8220;next_prev_arrows_overlaid&#8220; flickity_overflow=&#8220;hidden&#8220; flickity_wrap_around=&#8220;wrap&#8220; flickity_desktop_columns=&#8220;1&#8243; flickity_small_desktop_columns=&#8220;1&#8243; flickity_tablet_columns=&#8220;1&#8243; flickity_phone_columns=&#8220;1&#8243; flickity_autoplay=&#8220;true&#8220; flickity_box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; onclick=&#8220;link_image&#8220; img_size=&#8220;1920&#215;1080&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;4%&#8220; constrain_group_1=&#8220;yes&#8220; bottom_padding=&#8220;4%&#8220; top_margin=&#8220;4%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;clip-path&#8220; clip_path_animation_type=&#8220;scroll&#8220; clip_path_animation_applies=&#8220;row&#8220; clip_path_start_left_desktop=&#8220;0&#8243; clip_path_end_right_desktop=&#8220;15%&#8220; animation_trigger_offset=&#8220;0.00,100.00&#8243; animation_trigger_origin=&#8220;top&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#d6d7d8&#8243; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_row_inner column_margin=&#8220;20px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;8%&#8220; left_padding_desktop=&#8220;4%&#8220; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;4%&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;1132&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744389806949{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">1 Bett<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744389168294{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]Doppelbett[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;1135&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1740146816103{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">Wifi<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1740146826277{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]Kostenloser Internetzugang im gesamten Hotel[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;1078&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744282484107{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">Balkon<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744389147390{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]Balkon mit Panoramablick[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;1081&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1740146952013{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">Klimager\u00e4t<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1740146850653{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]Perfekter Komfort zu jeder Jahreszeit[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-12&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;20px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;8%&#8220; left_padding_desktop=&#8220;4%&#8220; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;4%&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;3137&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744388142090{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">Komfort<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1745426603336{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]TV, Safe und K\u00fchlschrank[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;3131&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744389098111{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">Sprudelbad<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1745944875509{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]Privater Whirlpool + freier Eintritt ins Spa[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;2886&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744390555358{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">K\u00fcche<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744390593989{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]voll ausgestattete K\u00fcche[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-6&#8243;][image_with_animation image_url=&#8220;1123&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;custom&#8220; max_width_custom=&#8220;20%&#8220;][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1740146906206{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h5 style=\"border-bottom: 1px solid #243449; display: inline; padding-bottom: 2px;\">Haustierfreundlich<\/h5>\n[\/vc_column_text][vc_column_text css_animation=&#8220;none&#8220; css=&#8220;.vc_custom_1744278418509{margin-bottom: 15px !important;padding-right: 20px !important;}&#8220; text_direction=&#8220;default&#8220;]T\u00e4gliche Kosten, kostenloses Willkommenspaket[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/5&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220; offset=&#8220;vc_col-xs-12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;30px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;8%&#8220; left_padding_desktop=&#8220;4%&#8220; right_padding_desktop=&#8220;4%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;dark&#8220; id=&#8220;request&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; zindex=&#8220;999&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css_animation=&#8220;fadeInUp&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>\nein Angebot anfordern<\/h2>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;5vh&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_global_section id=&#8220;6282&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;8%&#8220; bottom_padding=&#8220;4%&#8220; left_padding_desktop=&#8220;2%&#8220; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;2%&#8220; bottom_padding_tablet=&#8220;14%&#8220; bottom_padding_phone=&#8220;26%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;11\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;2%&#8220; left_padding_desktop=&#8220;8%&#8220; constrain_group_2=&#8220;yes&#8220; right_padding_desktop=&#8220;8%&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>Alle R\u00e4ume<\/h2>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][nectar_post_grid post_type=&#8220;custom&#8220; cpt_name=&#8220;camere&#8220; order=&#8220;DESC&#8220; orderby=&#8220;date&#8220; flickity_controls=&#8220;next_prev_arrows_overlaid&#8220; flickity_overflow=&#8220;hidden&#8220; flickity_wrap_around=&#8220;wrap&#8220; columns=&#8220;4&#8243; columns_tablet=&#8220;default&#8220; columns_phone=&#8220;default&#8220; desktop_small_cols_flickity=&#8220;4&#8243; tablet_cols_flickity=&#8220;2&#8243; phone_cols_flickity=&#8220;1&#8243; grid_item_spacing=&#8220;25px&#8220; grid_item_height=&#8220;80vh&#8220; 4_col_masonry_layout=&#8220;default&#8220; image_size=&#8220;large&#8220; overlaid_aspect_ratio_image_size=&#8220;yes&#8220; overlaid_custom_image_aspect_ratio=&#8220;4-5&#8243; image_loading=&#8220;default&#8220; animation=&#8220;fade-in-from-bottom&#8220; animation_stagger=&#8220;90&#8243; animation_easing=&#8220;default&#8220; heading_tag=&#8220;default&#8220; heading_tag_render=&#8220;default&#8220; font_size_min=&#8220;16&#8243; font_size_max=&#8220;22&#8243; category_position=&#8220;default&#8220; additional_meta_size=&#8220;default&#8220; custom_fields_location=&#8220;before_post_meta&#8220; custom_fields=&#8220;%5B%5D&#8220; grid_style=&#8220;content_overlaid&#8220; text_content_layout=&#8220;all_top_left&#8220; color_overlay=&#8220;#2f373f&#8220; color_overlay_opacity=&#8220;0.1&#8243; color_overlay_hover_opacity=&#8220;0.6&#8243; text_color=&#8220;light&#8220; text_color_hover=&#8220;light&#8220; text_opacity=&#8220;1&#8243; text_hover_opacity=&#8220;1&#8243; hover_effect=&#8220;zoom&#8220; border_radius=&#8220;none&#8220; posts_per_page=&#8220;20&#8243; display_type=&#8220;carousel&#8220; custom_font_size=&#8220;20&#8243;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_image=&#8220;715&#8243; bg_position=&#8220;left top&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10%&#8220; bottom_padding=&#8220;8%&#8220; top_padding_tablet=&#8220;20%&#8220; left_padding_tablet=&#8220;0&#8243; right_padding_tablet=&#8220;0&#8243; top_padding_phone=&#8220;34%&#8220; left_padding_phone=&#8220;0&#8243; right_padding_phone=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;&#8230;<\/p>\n","protected":false},"featured_media":3746,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4236","camere","type-camere","status-publish","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Einzimmerwohnung mit Jacuzzi in Trient | Hi Hotels Trento<\/title>\n<meta name=\"description\" content=\"Suite mit Panoramaterrasse und Whirlpool, Blick auf die Stadt und die Berge. Voll ausgestattete K\u00fcche, Spa und Pool inklusive. Luxus und Entspannung garantiert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einzimmerwohnung mit Jacuzzi in Trient | Hi Hotels Trento\" \/>\n<meta property=\"og:description\" content=\"Suite mit Panoramaterrasse und Whirlpool, Blick auf die Stadt und die Berge. Voll ausgestattete K\u00fcche, Spa und Pool inklusive. Luxus und Entspannung garantiert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/\" \/>\n<meta property=\"og:site_name\" content=\"Hi Hotels Trento\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T11:26:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/\",\"url\":\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/\",\"name\":\"Einzimmerwohnung mit Jacuzzi in Trient | Hi Hotels Trento\",\"isPartOf\":{\"@id\":\"https:\/\/www.hihotels.it\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg\",\"datePublished\":\"2025-04-11T15:58:04+00:00\",\"dateModified\":\"2025-11-05T11:26:10+00:00\",\"description\":\"Suite mit Panoramaterrasse und Whirlpool, Blick auf die Stadt und die Berge. Voll ausgestattete K\u00fcche, Spa und Pool inklusive. Luxus und Entspannung garantiert.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#primaryimage\",\"url\":\"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg\",\"contentUrl\":\"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hihotels.it\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einzimmerwohnung mit Jacuzzi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hihotels.it\/de\/#website\",\"url\":\"https:\/\/www.hihotels.it\/de\/\",\"name\":\"Hi Hotels Trento\",\"description\":\"Il tuo viaggio inizia ora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hihotels.it\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einzimmerwohnung mit Jacuzzi in Trient | Hi Hotels Trento","description":"Suite mit Panoramaterrasse und Whirlpool, Blick auf die Stadt und die Berge. Voll ausgestattete K\u00fcche, Spa und Pool inklusive. Luxus und Entspannung garantiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/","og_locale":"de_DE","og_type":"article","og_title":"Einzimmerwohnung mit Jacuzzi in Trient | Hi Hotels Trento","og_description":"Suite mit Panoramaterrasse und Whirlpool, Blick auf die Stadt und die Berge. Voll ausgestattete K\u00fcche, Spa und Pool inklusive. Luxus und Entspannung garantiert.","og_url":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/","og_site_name":"Hi Hotels Trento","article_modified_time":"2025-11-05T11:26:10+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/","url":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/","name":"Einzimmerwohnung mit Jacuzzi in Trient | Hi Hotels Trento","isPartOf":{"@id":"https:\/\/www.hihotels.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#primaryimage"},"image":{"@id":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg","datePublished":"2025-04-11T15:58:04+00:00","dateModified":"2025-11-05T11:26:10+00:00","description":"Suite mit Panoramaterrasse und Whirlpool, Blick auf die Stadt und die Berge. Voll ausgestattete K\u00fcche, Spa und Pool inklusive. Luxus und Entspannung garantiert.","breadcrumb":{"@id":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#primaryimage","url":"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg","contentUrl":"https:\/\/www.hihotels.it\/wp-content\/uploads\/2025\/04\/hihotels-trento-camera-monolocale-con-con-jacuzzi-0.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.hihotels.it\/de\/zimmer\/einzimmerwohnung-mit-jacuzzi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hihotels.it\/de\/"},{"@type":"ListItem","position":2,"name":"Einzimmerwohnung mit Jacuzzi"}]},{"@type":"WebSite","@id":"https:\/\/www.hihotels.it\/de\/#website","url":"https:\/\/www.hihotels.it\/de\/","name":"Hi Hotels Trento","description":"Il tuo viaggio inizia ora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hihotels.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:40:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hihotels.it\/de\/wp-json\/wp\/v2\/camere\/4236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hihotels.it\/de\/wp-json\/wp\/v2\/camere"}],"about":[{"href":"https:\/\/www.hihotels.it\/de\/wp-json\/wp\/v2\/types\/camere"}],"version-history":[{"count":1,"href":"https:\/\/www.hihotels.it\/de\/wp-json\/wp\/v2\/camere\/4236\/revisions"}],"predecessor-version":[{"id":6384,"href":"https:\/\/www.hihotels.it\/de\/wp-json\/wp\/v2\/camere\/4236\/revisions\/6384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hihotels.it\/de\/wp-json\/wp\/v2\/media\/3746"}],"wp:attachment":[{"href":"https:\/\/www.hihotels.it\/de\/wp-json\/wp\/v2\/media?parent=4236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}